{"id":965,"date":"2024-02-03T14:56:11","date_gmt":"2024-02-03T13:56:11","guid":{"rendered":"https:\/\/weltlaeden.de\/kupferdreh\/?p=965"},"modified":"2024-02-03T14:57:52","modified_gmt":"2024-02-03T13:57:52","slug":"eu-lieferkette","status":"publish","type":"post","link":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/","title":{"rendered":"EU-Lieferkette"},"content":{"rendered":"<h1>FDP droht EU-Lieferkettengesetz zu verhindern!<\/h1>\n<p>Die FDP hatte sich noch 2021 im Ampel-Koalitionsvertrag f\u00fcr ein EU-einheitliches Lieferkettengesetz ausgesprochen, nun ist ihr der EU-Entwurf (der schon ein Kompromis ist) zu kompliziert.<\/p>\n<p>Aus FDP Sicht verursacht die Umsetzung eines solchen Gesetzes einen Wust an B\u00fcrokratie. Die FDP dr\u00e4ngt die Bundesregierung, sich bei der Abstimmung im EU-Rat zu enthalten &#8211; dies k\u00f6nnte das Ende eines EU-einheitlichen Vorgehens gegen Zwangs- und Kinderarbeit in den globalen Lieferketten bedeuten. Lesen Sie <a href=\"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2024\/02\/24-Lieferkette-EU.pdf\" target=\"_blank\" rel=\"noopener\">hier<\/a> den Artikel aus der Rheinischen Post. &#8212;- Die Entwicklungsministerin Schulze (SPD) hat&#8217;s nicht leicht mit der Ampel!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FDP droht EU-Lieferkettengesetz zu verhindern! Die FDP hatte sich noch 2021 im Ampel-Koalitionsvertrag f\u00fcr ein EU-einheitliches Lieferkettengesetz ausgesprochen, nun ist ihr der EU-Entwurf (der schon ein Kompromis ist) zu kompliziert. Aus FDP Sicht verursacht die Umsetzung eines solchen Gesetzes einen Wust an B\u00fcrokratie. Die FDP dr\u00e4ngt die Bundesregierung, sich bei der Abstimmung im EU-Rat zu&hellip;<\/p>\n","protected":false},"author":85,"featured_media":669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-1","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EU-Lieferkette - Weltladen Kupferdreh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EU-Lieferkette - Weltladen Kupferdreh\" \/>\n<meta property=\"og:description\" content=\"FDP droht EU-Lieferkettengesetz zu verhindern! Die FDP hatte sich noch 2021 im Ampel-Koalitionsvertrag f\u00fcr ein EU-einheitliches Lieferkettengesetz ausgesprochen, nun ist ihr der EU-Entwurf (der schon ein Kompromis ist) zu kompliziert. Aus FDP Sicht verursacht die Umsetzung eines solchen Gesetzes einen Wust an B\u00fcrokratie. Die FDP dr\u00e4ngt die Bundesregierung, sich bei der Abstimmung im EU-Rat zu&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/\" \/>\n<meta property=\"og:site_name\" content=\"Weltladen Kupferdreh\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-03T13:56:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-03T13:57:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"229\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kupferdreh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"kupferdreh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/\"},\"author\":{\"name\":\"kupferdreh\",\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/#\/schema\/person\/b0e74df54ae601d4659c73829b66b2ee\"},\"headline\":\"EU-Lieferkette\",\"datePublished\":\"2024-02-03T13:56:11+00:00\",\"dateModified\":\"2024-02-03T13:57:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/\"},\"wordCount\":98,\"image\":{\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg\",\"articleSection\":[\"Keine Kategorie\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/\",\"url\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/\",\"name\":\"EU-Lieferkette - Weltladen Kupferdreh\",\"isPartOf\":{\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg\",\"datePublished\":\"2024-02-03T13:56:11+00:00\",\"dateModified\":\"2024-02-03T13:57:52+00:00\",\"author\":{\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/#\/schema\/person\/b0e74df54ae601d4659c73829b66b2ee\"},\"breadcrumb\":{\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#primaryimage\",\"url\":\"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg\",\"contentUrl\":\"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg\",\"width\":420,\"height\":229},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/weltlaeden.de\/kupferdreh\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EU-Lieferkette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/#website\",\"url\":\"https:\/\/weltlaeden.de\/kupferdreh\/\",\"name\":\"Vorlage\",\"description\":\"Faire Produkte seit 1994\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/weltlaeden.de\/kupferdreh\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/#\/schema\/person\/b0e74df54ae601d4659c73829b66b2ee\",\"name\":\"kupferdreh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/weltlaeden.de\/kupferdreh\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2f8b92883cfaac4a1903f025e7177da3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2f8b92883cfaac4a1903f025e7177da3?s=96&d=mm&r=g\",\"caption\":\"kupferdreh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EU-Lieferkette - Weltladen Kupferdreh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/","og_locale":"de_DE","og_type":"article","og_title":"EU-Lieferkette - Weltladen Kupferdreh","og_description":"FDP droht EU-Lieferkettengesetz zu verhindern! Die FDP hatte sich noch 2021 im Ampel-Koalitionsvertrag f\u00fcr ein EU-einheitliches Lieferkettengesetz ausgesprochen, nun ist ihr der EU-Entwurf (der schon ein Kompromis ist) zu kompliziert. Aus FDP Sicht verursacht die Umsetzung eines solchen Gesetzes einen Wust an B\u00fcrokratie. Die FDP dr\u00e4ngt die Bundesregierung, sich bei der Abstimmung im EU-Rat zu&hellip;","og_url":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/","og_site_name":"Weltladen Kupferdreh","article_published_time":"2024-02-03T13:56:11+00:00","article_modified_time":"2024-02-03T13:57:52+00:00","og_image":[{"width":420,"height":229,"url":"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg","type":"image\/jpeg"}],"author":"kupferdreh","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"kupferdreh","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#article","isPartOf":{"@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/"},"author":{"name":"kupferdreh","@id":"https:\/\/weltlaeden.de\/kupferdreh\/#\/schema\/person\/b0e74df54ae601d4659c73829b66b2ee"},"headline":"EU-Lieferkette","datePublished":"2024-02-03T13:56:11+00:00","dateModified":"2024-02-03T13:57:52+00:00","mainEntityOfPage":{"@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/"},"wordCount":98,"image":{"@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#primaryimage"},"thumbnailUrl":"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg","articleSection":["Keine Kategorie"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/","url":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/","name":"EU-Lieferkette - Weltladen Kupferdreh","isPartOf":{"@id":"https:\/\/weltlaeden.de\/kupferdreh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#primaryimage"},"image":{"@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#primaryimage"},"thumbnailUrl":"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg","datePublished":"2024-02-03T13:56:11+00:00","dateModified":"2024-02-03T13:57:52+00:00","author":{"@id":"https:\/\/weltlaeden.de\/kupferdreh\/#\/schema\/person\/b0e74df54ae601d4659c73829b66b2ee"},"breadcrumb":{"@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#primaryimage","url":"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg","contentUrl":"https:\/\/weltlaeden.de\/kupferdreh\/wp-content\/uploads\/sites\/57\/2021\/02\/Initiative-Lieferkette.jpg","width":420,"height":229},{"@type":"BreadcrumbList","@id":"https:\/\/weltlaeden.de\/kupferdreh\/eu-lieferkette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/weltlaeden.de\/kupferdreh\/"},{"@type":"ListItem","position":2,"name":"EU-Lieferkette"}]},{"@type":"WebSite","@id":"https:\/\/weltlaeden.de\/kupferdreh\/#website","url":"https:\/\/weltlaeden.de\/kupferdreh\/","name":"Vorlage","description":"Faire Produkte seit 1994","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weltlaeden.de\/kupferdreh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/weltlaeden.de\/kupferdreh\/#\/schema\/person\/b0e74df54ae601d4659c73829b66b2ee","name":"kupferdreh","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/weltlaeden.de\/kupferdreh\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f8b92883cfaac4a1903f025e7177da3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f8b92883cfaac4a1903f025e7177da3?s=96&d=mm&r=g","caption":"kupferdreh"}}]}},"_links":{"self":[{"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/posts\/965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/comments?post=965"}],"version-history":[{"count":6,"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/posts\/965\/revisions"}],"predecessor-version":[{"id":971,"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/posts\/965\/revisions\/971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/media\/669"}],"wp:attachment":[{"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/media?parent=965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/categories?post=965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weltlaeden.de\/kupferdreh\/wp-json\/wp\/v2\/tags?post=965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}