{"id":59,"count":1,"description":"","link":"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/","name":"WL Alzey","slug":"wl-alzey","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WL Alzey Archive - Weltladen Alzey e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WL Alzey Archive - Weltladen Alzey e.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/\" \/>\n<meta property=\"og:site_name\" content=\"Weltladen Alzey e.V.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/\",\"url\":\"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/\",\"name\":\"WL Alzey Archive - Weltladen Alzey e.V.\",\"isPartOf\":{\"@id\":\"https:\/\/weltlaeden.de\/alzey\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/weltlaeden.de\/alzey\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WL Alzey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/weltlaeden.de\/alzey\/#website\",\"url\":\"https:\/\/weltlaeden.de\/alzey\/\",\"name\":\"Vorlage\",\"description\":\"Faire Produkte seit 1983\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/weltlaeden.de\/alzey\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WL Alzey Archive - Weltladen Alzey e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/","og_locale":"de_DE","og_type":"article","og_title":"WL Alzey Archive - Weltladen Alzey e.V.","og_url":"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/","og_site_name":"Weltladen Alzey e.V.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/","url":"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/","name":"WL Alzey Archive - Weltladen Alzey e.V.","isPartOf":{"@id":"https:\/\/weltlaeden.de\/alzey\/#website"},"breadcrumb":{"@id":"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/weltlaeden.de\/alzey\/tag\/wl-alzey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/weltlaeden.de\/alzey\/"},{"@type":"ListItem","position":2,"name":"WL Alzey"}]},{"@type":"WebSite","@id":"https:\/\/weltlaeden.de\/alzey\/#website","url":"https:\/\/weltlaeden.de\/alzey\/","name":"Vorlage","description":"Faire Produkte seit 1983","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weltlaeden.de\/alzey\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/weltlaeden.de\/alzey\/wp-json\/wp\/v2\/tags\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weltlaeden.de\/alzey\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/weltlaeden.de\/alzey\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/weltlaeden.de\/alzey\/wp-json\/wp\/v2\/posts?tags=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}